{"id":293,"count":26,"description":"","link":"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/","name":"Wasserwirtschaft","slug":"wasserwirtschaft","taxonomy":"tribe_events_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wasserwirtschaft Archive - Ingenieurkammer Th\u00fcringen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wasserwirtschaft Archive - Ingenieurkammer Th\u00fcringen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Ingenieurkammer Th\u00fcringen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/\",\"url\":\"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/\",\"name\":\"Wasserwirtschaft Archive - Ingenieurkammer Th\u00fcringen\",\"isPartOf\":{\"@id\":\"https:\/\/ikth.de\/startseite\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/ikth.de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wasserwirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ikth.de\/startseite\/#website\",\"url\":\"https:\/\/ikth.de\/startseite\/\",\"name\":\"Ingenieurkammer Th\u00fcringen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ikth.de\/startseite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wasserwirtschaft Archive - Ingenieurkammer Th\u00fcringen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Wasserwirtschaft Archive - Ingenieurkammer Th\u00fcringen","og_url":"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/","og_site_name":"Ingenieurkammer Th\u00fcringen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/","url":"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/","name":"Wasserwirtschaft Archive - Ingenieurkammer Th\u00fcringen","isPartOf":{"@id":"https:\/\/ikth.de\/startseite\/#website"},"breadcrumb":{"@id":"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/ikth.de\/startseite\/veranstaltungen\/kategorie\/wasserwirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ikth.de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Wasserwirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/ikth.de\/startseite\/#website","url":"https:\/\/ikth.de\/startseite\/","name":"Ingenieurkammer Th\u00fcringen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ikth.de\/startseite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events_cat\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}