{"id":7325,"date":"2024-08-01T09:28:34","date_gmt":"2024-08-01T07:28:34","guid":{"rendered":"https:\/\/ikth.de\/startseite\/?post_type=tribe_events&#038;p=7325"},"modified":"2024-08-14T14:04:03","modified_gmt":"2024-08-14T12:04:03","slug":"praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung","status":"publish","type":"tribe_events","link":"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/","title":{"rendered":"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung"},"content":{"rendered":"<p><strong>Dipl.-Ing. J\u00fcrgen G\u00e4n\u00dfmantel, Beratender Ingenieur<\/strong><\/p>\n<p>In der Planung, Bau\u00fcberwachung und Ausf\u00fchrung nachhaltiger Geb\u00e4ude k\u00f6nnen durch aufmerksames und sorgf\u00e4ltiges Arbeiten bereits fr\u00fchzeitig Sch\u00e4den vermieden werden. Gerade im Bereich der energetischen Sanierung gibt es hier typische Stolperfallen, die beispielsweise Planung und Bau\u00fcberwachung vor Herausforderungen stellen und, wenn unsauber gearbeitet wird, zu vermeidbaren Schadensf\u00e4llen f\u00fchren.<\/p>\n<p>&nbsp;<\/p>\n<h4>Programm<\/h4>\n<p>In der Planung, Bau\u00fcberwachung und Ausf\u00fchrung nachhaltiger Geb\u00e4ude k\u00f6nnen durch aufmerksames und sorgf\u00e4ltiges Arbeiten bereits fr\u00fchzeitig Sch\u00e4den vermieden werden. Gerade im Bereich der energetischen Sanierung gibt es hier typische Stolperfallen, die beispielsweise Planung und Bau\u00fcberwachung vor Herausforderungen stellen und, wenn unsauber gearbeitet wird, zu vermeidbaren Schadensf\u00e4llen f\u00fchren.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Die Veranstaltung ist durch die IKTh mit 2 WB-Stunden anerkannt.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/wienerberger-wissen.de\/online-fortbildungen\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung-2\/\" target=\"_blank\" rel=\"noopener\"><strong>Weitere Informationen<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dipl.-Ing. J\u00fcrgen G\u00e4n\u00dfmantel, Beratender Ingenieur In der Planung, Bau\u00fcberwachung und Ausf\u00fchrung nachhaltiger Geb\u00e4ude k\u00f6nnen durch aufmerksames und sorgf\u00e4ltiges Arbeiten bereits fr\u00fchzeitig Sch\u00e4den vermieden werden. Gerade im Bereich der energetischen Sanierung&hellip;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"tribe_events_cat":[305,304,42],"class_list":["post-7325","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-bauwesen","tribe_events_cat-nachhaltigkeit","tribe_events_cat-online-veranstaltung","cat_bauwesen","cat_nachhaltigkeit","cat_online-veranstaltung","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung - Ingenieurkammer Th\u00fcringen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung - Ingenieurkammer Th\u00fcringen\" \/>\n<meta property=\"og:description\" content=\"Dipl.-Ing. J\u00fcrgen G\u00e4n\u00dfmantel, Beratender Ingenieur In der Planung, Bau\u00fcberwachung und Ausf\u00fchrung nachhaltiger Geb\u00e4ude k\u00f6nnen durch aufmerksames und sorgf\u00e4ltiges Arbeiten bereits fr\u00fchzeitig Sch\u00e4den vermieden werden. Gerade im Bereich der energetischen Sanierung&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/\" \/>\n<meta property=\"og:site_name\" content=\"Ingenieurkammer Th\u00fcringen\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-14T12:04:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/\",\"url\":\"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/\",\"name\":\"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung - Ingenieurkammer Th\u00fcringen\",\"isPartOf\":{\"@id\":\"https:\/\/ikth.de\/startseite\/#website\"},\"datePublished\":\"2024-08-01T07:28:34+00:00\",\"dateModified\":\"2024-08-14T12:04:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/ikth.de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\/\/ikth.de\/startseite\/veranstaltungen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ikth.de\/startseite\/#website\",\"url\":\"https:\/\/ikth.de\/startseite\/\",\"name\":\"Ingenieurkammer Th\u00fcringen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ikth.de\/startseite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung - Ingenieurkammer Th\u00fcringen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/","og_locale":"de_DE","og_type":"article","og_title":"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung - Ingenieurkammer Th\u00fcringen","og_description":"Dipl.-Ing. J\u00fcrgen G\u00e4n\u00dfmantel, Beratender Ingenieur In der Planung, Bau\u00fcberwachung und Ausf\u00fchrung nachhaltiger Geb\u00e4ude k\u00f6nnen durch aufmerksames und sorgf\u00e4ltiges Arbeiten bereits fr\u00fchzeitig Sch\u00e4den vermieden werden. Gerade im Bereich der energetischen Sanierung&hellip;","og_url":"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/","og_site_name":"Ingenieurkammer Th\u00fcringen","article_modified_time":"2024-08-14T12:04:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/","url":"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/","name":"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung - Ingenieurkammer Th\u00fcringen","isPartOf":{"@id":"https:\/\/ikth.de\/startseite\/#website"},"datePublished":"2024-08-01T07:28:34+00:00","dateModified":"2024-08-14T12:04:03+00:00","breadcrumb":{"@id":"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ikth.de\/startseite\/event\/praevention-von-schaeden-und-maengeln-in-der-planung-und-ausfuehrung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ikth.de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/ikth.de\/startseite\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Pr\u00e4vention von Sch\u00e4den und M\u00e4ngeln in der Planung und Ausf\u00fchrung"}]},{"@type":"WebSite","@id":"https:\/\/ikth.de\/startseite\/#website","url":"https:\/\/ikth.de\/startseite\/","name":"Ingenieurkammer Th\u00fcringen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ikth.de\/startseite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events\/7325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/comments?post=7325"}],"version-history":[{"count":3,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events\/7325\/revisions"}],"predecessor-version":[{"id":7383,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events\/7325\/revisions\/7383"}],"wp:attachment":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/media?parent=7325"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tags?post=7325"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/tribe_events_cat?post=7325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}