{"id":2171,"date":"2021-06-24T08:22:13","date_gmt":"2021-06-24T06:22:13","guid":{"rendered":"https:\/\/ikth.de\/startseite\/project\/dompalais-erfurt-hoffman-seifert-partner-copy\/"},"modified":"2021-09-16T08:48:55","modified_gmt":"2021-09-16T06:48:55","slug":"abwasserbeseitigung-werratal-wiesgrund","status":"publish","type":"dt_portfolio","link":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/","title":{"rendered":"Abwasserbeseitigung Werratal &#8211; Wiesgrund"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"dt-fancy-separator h1-size style-disabled\" style=\"width: 100%;\"><div class=\"dt-fancy-title\"><span class=\"separator-holder separator-left\"><\/span>Abwasserbeseitigung Werratal - Wiesgrund<span class=\"separator-holder separator-right\"><\/span><\/div><\/div>[vc_empty_space][vc_row_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Im s\u00fcdth\u00fcringer Einzugsgebiet des Werratals bei Meiningen waren umfangreiche Planungen f\u00fcr die abwasserseitige Erschlie\u00dfung von insgesamt zehn Ortschaften notwendig. Dabei mussten f\u00fcr die Ortslagen entsprechende Generalentw\u00e4sserungspl\u00e4ne sowie ein Gesamtkonzept zur Abwasser\u00fcberleitung und -reinigung angefertigt werden. F\u00fcr die zentrale Abwasserreinigung wurde eine Kl\u00e4ranlage zwischen Ober- und Unterma\u00dffeld im sogenannten Gleisdreieck f\u00fcr insgesamt 7.400\u00a0EW (Einwohnerwerte) errichtet.<\/p>\n<p>Aufgrund der Topografie und der N\u00e4he zur Werra (Gew\u00e4sser 1. Ordnung und FFH-Gebiet) waren mehrere Querungen des Vorfluters, verschiedener Bundes- und Landesstra\u00dfen sowie vorhandener Gleisanlagen der Deutschen Bahn notwendig. Die \u00dcberleitungen wurden mittels Pumpwerke als Druckentw\u00e4sserung ausgebildet. Eins dieser Pumpwerke musste in der bestehenden Justizvollzugsanstalt Unterma\u00dffeld als Mischwasserpumpwerk hergestellt werden. Ferner waren zahlreiche Mischwasserbehandlungsanlagen teilweise im \u00dcberschwemmungsgebiet der Werra zu errichten. Schwierige Baugrundverh\u00e4ltnisse, die Ber\u00fccksichtigung der bestehenden Vegetation im FFH-Gebiet sowie oft zu benutzende Privatgrundst\u00fccke stellten gro\u00dfe Anforderungen an die Planung und Bau\u00fcberwachung der Ma\u00dfnahmen.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Fotos: HOFFMANN.SEIFERT.PARTNER architekten ingenieure<\/em>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;]<div class=\"dt-fancy-separator title-left h4-size style-disabled\" style=\"width: 100%;\"><div class=\"dt-fancy-title\" style=\"color: #005091;\"><span class=\"separator-holder separator-left\"><\/span>Verantwortliches Kammermitglied:<span class=\"separator-holder separator-right\"><\/span><\/div><\/div>[vc_column_text]Sascha K\u00fcck<br \/>\nHOFFMANN.SEIFERT.PARTNER<br \/>\narchitekten ingenieure<br \/>\nNeundorfer Stra\u00dfe 2<br \/>\n98527 Suhl[\/vc_column_text][vc_empty_space height=&#8220;10px&#8220;][vc_separator]<div id=\"ultimate-heading-22746a04c246dea2f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-22746a04c246dea2f uvc-6325  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-22746a04c246dea2f h4'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h4 style=\"--font-weight:theme;\">Daten und Fakten<\/h4><\/div><\/div>[vc_empty_space height=&#8220;10px&#8220;][vc_column_text]<strong>Vorhaben: <\/strong>Abwasserbeseitigung Werratal &#8211; Wiesgrund<\/p>\n<p><strong>Auftraggeber: <\/strong>Kommunaler Wasser- und Abwasserzweckverband Meininger Umland (KWA)<\/p>\n<p><strong>Standort: <\/strong>Meininger Umland<\/p>\n<p><strong>Leistungen: <\/strong>Abwasserbeseitigung, Konstruktiver Ingenieurbau, Tragwerksplanung<\/p>\n<p><strong>Besonderheiten: <\/strong>Bau im \u00dcberschwemmungsgebiet, Bauma\u00dfnahmen innerhalb einer Justizvollzugsanstalt, Druckentw\u00e4sserung, Errichtung von zwei Kl\u00e4ranlagen, Tragwerksplanung, Objektplanung, Technische Ausr\u00fcstung, Bauoberleitung[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;vc_default&#8220; full_width=&#8220;stretch_row_content&#8220;][vc_column]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div {\n  width: 36px;\n  height: 36px;\n  border-radius: 500px;\n}\n.dt-arrow-border-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div:not(:hover):before {\n  border-width: 0px;\n}\n.dt-arrow-hover-border-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div:hover:after {\n  border-width: 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div.owl-prev {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  left: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div.owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div.owl-prev i {\n  padding: 0px 0px 0px 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div.owl-next {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  right: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div.owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div.owl-next i {\n  padding: 0px 0px 0px 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav i {\n  font-size: 18px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div:not(:hover) i,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div:not(:hover) i:before {\n  color: #ffffff;\n  background: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div:hover i,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.owl-carousel .owl-nav div:hover i:before {\n  color: rgba(255,255,255,0.75);\n  background: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc .owl-dots {\n  top: calc(100% + 20px);\n  left: 50%;\n  transform: translateX(calc(-50% + 0px));\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc .owl-dots {\n    transform: translateX(-50%);\n    margin-left: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc .owl-dot {\n  width: 10px;\n  height: 10px;\n  margin: 0 8px;\n}\n@media screen and (max-width: 778px) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.hide-arrows .owl-nav a {\n    display: none;\n  }\n}\n@media screen and (max-width: 778px) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.reposition-arrows .owl-nav div.owl-prev {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    left: 10px;\n  }\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.reposition-arrows .owl-nav div.owl-next {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    right: 10px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.reposition-arrows .owl-nav div.owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.reposition-arrows .owl-nav div.owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc figure,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc .rollover,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc img,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc .gallery-rollover {\n  border-radius: 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.enable-bg-rollover .gallery-rollover {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.enable-img-shadow .owl-stage-outer {\n  padding: 14px 0;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.enable-bg-rollover.hover-scale figure .rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.gallery-shortcode .gallery-zoom-ico {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: -22px 0 0 -22px;\n  border-width: 0px;\n}\n.dt-icon-bg-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.gallery-shortcode .gallery-zoom-ico {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.gallery-shortcode .gallery-zoom-ico:before,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc.gallery-shortcode .gallery-zoom-ico span {\n  font-size: 32px;\n  line-height: 44px;\n  color: #ffffff;\n  background: none;\n}<\/style><div class=\"owl-carousel gallery-carousel-shortcode gallery-shortcode  dt-gallery-container dt-owl-carousel-call gallery-carousel-shortcode-id-fa238085c84d87538e89edfee25cdbfc quick-scale-img enable-bg-rollover meta-info-off dt-arrow-border-on dt-arrow-hover-border-on bullets-small-dot-stroke reposition-arrows dt-icon-bg-off arrows-bg-on disable-arrows-hover-bg arrows-hover-bg-on  hover-fade \" data-scroll-mode=\"1\" data-col-num=\"4\" data-wide-col-num=\"4\" data-laptop-col=\"4\" data-h-tablet-columns-num=\"4\" data-v-tablet-columns-num=\"3\" data-phone-columns-num=\"1\" data-col-gap=\"10\" data-stage-padding=\"0\" data-speed=\"600\" data-autoplay=\"true\" data-autoplay_speed=\"4000\" data-arrows=\"false\" data-bullet=\"true\" data-next-icon=\"icon-ar-017-r\" data-prev-icon=\"icon-ar-017-l\" data-img-shadow-size=\"12px\" data-img-shadow-spread=\"3px\"><div data-post-id=\"2178\" data-date=\"2021-06-24T08:28:03+02:00\" data-name=\"DSCI0030\"><figure class=\"post\"><a href=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0030.jpg\" class=\"rollover dt-pswp-item\" data-large_image_width=\"1200\" data-large_image_height=\"751\" data-dt-img-description=\"\" title=\"DSCI0030\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0030-1126x751.jpg\" srcset=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0030-1126x751.jpg 1126w\" style=\"--ratio: 1126 \/ 751\" sizes=\"auto, (max-width: 1126px) 100vw, 1126px\" alt=\"\" width=\"1126\" height=\"751\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><div data-post-id=\"2177\" data-date=\"2021-06-24T08:28:00+02:00\" data-name=\"DSCI0022\"><figure class=\"post\"><a href=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0022.jpg\" class=\"rollover dt-pswp-item\" data-large_image_width=\"1200\" data-large_image_height=\"900\" data-dt-img-description=\"\" title=\"DSCI0022\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0022-1200x800.jpg\" srcset=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0022-1200x800.jpg 1200w\" style=\"--ratio: 1200 \/ 800\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" alt=\"\" width=\"1200\" height=\"800\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><div data-post-id=\"2175\" data-date=\"2021-06-24T08:27:54+02:00\" data-name=\"DSC04681\"><figure class=\"post\"><a href=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC04681.jpg\" class=\"rollover dt-pswp-item\" data-large_image_width=\"1200\" data-large_image_height=\"867\" data-dt-img-description=\"\" title=\"DSC04681\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC04681-1200x800.jpg\" srcset=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC04681-1200x800.jpg 1200w\" style=\"--ratio: 1200 \/ 800\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" alt=\"\" width=\"1200\" height=\"800\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><div data-post-id=\"2174\" data-date=\"2021-06-24T08:27:50+02:00\" data-name=\"PIC_1950\"><figure class=\"post\"><a href=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/PIC_1950.jpg\" class=\"rollover dt-pswp-item\" data-large_image_width=\"1200\" data-large_image_height=\"751\" data-dt-img-description=\"\" title=\"PIC_1950\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/PIC_1950-1126x751.jpg\" srcset=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/PIC_1950-1126x751.jpg 1126w\" style=\"--ratio: 1126 \/ 751\" sizes=\"auto, (max-width: 1126px) 100vw, 1126px\" alt=\"\" width=\"1126\" height=\"751\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><div data-post-id=\"2173\" data-date=\"2021-06-24T08:27:47+02:00\" data-name=\"DSCI0033\"><figure class=\"post\"><a href=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0033.jpg\" class=\"rollover dt-pswp-item\" data-large_image_width=\"1200\" data-large_image_height=\"867\" data-dt-img-description=\"\" title=\"DSCI0033\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0033-1200x800.jpg\" srcset=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSCI0033-1200x800.jpg 1200w\" style=\"--ratio: 1200 \/ 800\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" alt=\"\" width=\"1200\" height=\"800\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><\/div>[vc_empty_space height=&#8220;60px&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Im s\u00fcdth\u00fcringer Einzugsgebiet des Werratals bei Meiningen waren umfangreiche Planungen f\u00fcr die abwasserseitige Erschlie\u00dfung von insgesamt zehn Ortschaften notwendig. Dabei mussten f\u00fcr die Ortslagen entsprechende Generalentw\u00e4sserungspl\u00e4ne sowie ein Gesamtkonzept zur Abwasser\u00fcberleitung und -reinigung angefertigt werden. F\u00fcr die zentrale Abwasserreinigung wurde eine Kl\u00e4ranlage zwischen Ober- und Unterma\u00dffeld im sogenannten Gleisdreieck f\u00fcr insgesamt 7.400 EW (Einwohnerwerte) errichtet.<\/p>\n","protected":false},"author":3,"featured_media":2176,"template":"","dt_portfolio_category":[10],"dt_portfolio_tags":[],"class_list":["post-2171","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-projekte","dt_portfolio_category-10","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abwasserbeseitigung Werratal - Wiesgrund - Ingenieurkammer Th\u00fcringen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abwasserbeseitigung Werratal - Wiesgrund - Ingenieurkammer Th\u00fcringen\" \/>\n<meta property=\"og:description\" content=\"Im s\u00fcdth\u00fcringer Einzugsgebiet des Werratals bei Meiningen waren umfangreiche Planungen f\u00fcr die abwasserseitige Erschlie\u00dfung von insgesamt zehn Ortschaften notwendig. Dabei mussten f\u00fcr die Ortslagen entsprechende Generalentw\u00e4sserungspl\u00e4ne sowie ein Gesamtkonzept zur Abwasser\u00fcberleitung und -reinigung angefertigt werden. F\u00fcr die zentrale Abwasserreinigung wurde eine Kl\u00e4ranlage zwischen Ober- und Unterma\u00dffeld im sogenannten Gleisdreieck f\u00fcr insgesamt 7.400 EW (Einwohnerwerte) errichtet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/\" \/>\n<meta property=\"og:site_name\" content=\"Ingenieurkammer Th\u00fcringen\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-16T06:48:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/\",\"url\":\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/\",\"name\":\"Abwasserbeseitigung Werratal - Wiesgrund - Ingenieurkammer Th\u00fcringen\",\"isPartOf\":{\"@id\":\"https:\/\/ikth.de\/startseite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg\",\"datePublished\":\"2021-06-24T06:22:13+00:00\",\"dateModified\":\"2021-09-16T06:48:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#primaryimage\",\"url\":\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg\",\"contentUrl\":\"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg\",\"width\":1200,\"height\":867},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/ikth.de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/ikth.de\/startseite\/projekte-der-kammermitglieder\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abwasserbeseitigung Werratal &#8211; Wiesgrund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ikth.de\/startseite\/#website\",\"url\":\"https:\/\/ikth.de\/startseite\/\",\"name\":\"Ingenieurkammer Th\u00fcringen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ikth.de\/startseite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abwasserbeseitigung Werratal - Wiesgrund - Ingenieurkammer Th\u00fcringen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/","og_locale":"de_DE","og_type":"article","og_title":"Abwasserbeseitigung Werratal - Wiesgrund - Ingenieurkammer Th\u00fcringen","og_description":"Im s\u00fcdth\u00fcringer Einzugsgebiet des Werratals bei Meiningen waren umfangreiche Planungen f\u00fcr die abwasserseitige Erschlie\u00dfung von insgesamt zehn Ortschaften notwendig. Dabei mussten f\u00fcr die Ortslagen entsprechende Generalentw\u00e4sserungspl\u00e4ne sowie ein Gesamtkonzept zur Abwasser\u00fcberleitung und -reinigung angefertigt werden. F\u00fcr die zentrale Abwasserreinigung wurde eine Kl\u00e4ranlage zwischen Ober- und Unterma\u00dffeld im sogenannten Gleisdreieck f\u00fcr insgesamt 7.400 EW (Einwohnerwerte) errichtet.","og_url":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/","og_site_name":"Ingenieurkammer Th\u00fcringen","article_modified_time":"2021-09-16T06:48:55+00:00","og_image":[{"width":1200,"height":867,"url":"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/","url":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/","name":"Abwasserbeseitigung Werratal - Wiesgrund - Ingenieurkammer Th\u00fcringen","isPartOf":{"@id":"https:\/\/ikth.de\/startseite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#primaryimage"},"image":{"@id":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#primaryimage"},"thumbnailUrl":"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg","datePublished":"2021-06-24T06:22:13+00:00","dateModified":"2021-09-16T06:48:55+00:00","breadcrumb":{"@id":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#primaryimage","url":"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg","contentUrl":"https:\/\/ikth.de\/wp-content\/uploads\/2021\/06\/DSC09628.jpg","width":1200,"height":867},{"@type":"BreadcrumbList","@id":"https:\/\/ikth.de\/startseite\/project\/abwasserbeseitigung-werratal-wiesgrund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ikth.de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/ikth.de\/startseite\/projekte-der-kammermitglieder\/"},{"@type":"ListItem","position":3,"name":"Abwasserbeseitigung Werratal &#8211; Wiesgrund"}]},{"@type":"WebSite","@id":"https:\/\/ikth.de\/startseite\/#website","url":"https:\/\/ikth.de\/startseite\/","name":"Ingenieurkammer Th\u00fcringen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ikth.de\/startseite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/dt_portfolio\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/dt_portfolio\/2171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/media\/2176"}],"wp:attachment":[{"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/media?parent=2171"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/dt_portfolio_category?post=2171"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/ikth.de\/startseite\/wp-json\/wp\/v2\/dt_portfolio_tags?post=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}